{"id":15345,"date":"2017-03-13T14:22:49","date_gmt":"2017-03-13T14:22:49","guid":{"rendered":"https:\/\/energie.pt\/energie-world\/news\/reference-work-single-family-house\/"},"modified":"2025-01-24T10:47:31","modified_gmt":"2025-01-24T10:47:31","slug":"reference-work-single-family-house","status":"publish","type":"post","link":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/","title":{"rendered":"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE"},"content":{"rendered":"\n<p>Une maison situ\u00e9e dans la r\u00e9gion de l\u2019Alto Minho, \u00e0 l&#8217;architecture moderne et avec une conception minimaliste, \u00e9quip\u00e9e d&#8217;un plancher radiant sous micro-ciment et d&#8217;un syst\u00e8me d&#8217;huisseries Cortizo.<\/p>\n\n<p>An integral solution of Central Heating and Hot Water was chosen as the main image of the intended concept.<\/p>\n\n<p>The residence was equipped with an integral Thermodynamic Solar System, consisting of a SOLAR BLOCK 16, a heat production unit for the underfloor with 16 Thermodynamic Solar Panels, and an ECO 300is, a Hot Water production unit (DHW) with 2 Thermodynamic Solar Panels.<\/p>\n\n<p>The images demonstrate a perfect architectural integration of the Thermodynamic Solar Panel system, giving the residence a pleasant aspect in the landscape and harmoniously blending in with its surroundings.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une maison situ\u00e9e dans la r\u00e9gion de l\u2019Alto Minho, \u00e0 l&#8217;architecture moderne et avec une conception minimaliste, \u00e9quip\u00e9e d&#8217;un plancher radiant sous micro-ciment et d&#8217;un syst\u00e8me d&#8217;huisseries Cortizo. An integral solution of Central Heating and Hot Water was chosen as the main image of the intended concept. The residence was equipped with an integral Thermodynamic [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11237,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[135,262],"tags":[],"class_list":["post-15345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-world-energie"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"acf":{"data_bimensal_da_noticia":"March \/ 2017"},"cp_meta_data":{"_encloseme":["1"],"blocksy_post_meta_options":["a:1:{s:17:\"styles_descriptor\";a:3:{s:6:\"styles\";a:3:{s:7:\"desktop\";s:0:\"\";s:6:\"tablet\";s:0:\"\";s:6:\"mobile\";s:0:\"\";}s:12:\"google_fonts\";a:0:{}s:7:\"version\";i:6;}}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_data_bimensal_da_noticia":["field_627e65cc70022"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_wp_page_template":["default"],"_thumbnail_id":["11237"],"_last_translation_edit_mode":["translation-editor"],"stackable_optimized_css":[""],"stackable_optimized_css_raw":["a:0:{}"],"_yoast_wpseo_primary_category":["1"],"data_bimensal_da_noticia":["March \/ 2017"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>REFERENCE WORK \u2013 SINGLE FAMILY HOUSE - ENERGIE EST, Lda.<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE - ENERGIE EST, Lda.\" \/>\r\n<meta property=\"og:description\" content=\"Une maison situ\u00e9e dans la r\u00e9gion de l\u2019Alto Minho, \u00e0 l&#8217;architecture moderne et avec une conception minimaliste, \u00e9quip\u00e9e d&#8217;un plancher radiant sous micro-ciment et d&#8217;un syst\u00e8me d&#8217;huisseries Cortizo. An integral solution of Central Heating and Hot Water was chosen as the main image of the intended concept. The residence was equipped with an integral Thermodynamic [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/\" \/>\r\n<meta property=\"og:site_name\" content=\"ENERGIE EST, Lda.\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2017-03-13T14:22:49+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-01-24T10:47:31+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1563\" \/>\r\n\t<meta property=\"og:image:height\" content=\"826\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"catiarocha\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"catiarocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/\"},\"author\":{\"name\":\"catiarocha\",\"@id\":\"https:\/\/energie.pt\/en\/#\/schema\/person\/db40e6f91190f7c107f522c91d27873d\"},\"headline\":\"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE\",\"datePublished\":\"2017-03-13T14:22:49+00:00\",\"dateModified\":\"2025-01-24T10:47:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/\"},\"wordCount\":129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/energie.pt\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg\",\"articleSection\":[\"News\",\"World Energie\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/\",\"url\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/\",\"name\":\"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE - ENERGIE EST, Lda.\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg\",\"datePublished\":\"2017-03-13T14:22:49+00:00\",\"dateModified\":\"2025-01-24T10:47:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg\",\"width\":1563,\"height\":826},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"homepage\",\"item\":\"https:\/\/energie.pt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"World Energie\",\"item\":\"https:\/\/energie.pt\/en\/category\/world-energie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"News\",\"item\":\"https:\/\/energie.pt\/en\/category\/world-energie\/news\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energie.pt\/en\/#website\",\"url\":\"https:\/\/energie.pt\/en\/\",\"name\":\"ENERGIE\",\"description\":\"Thermodynamic Solar Energy Solutions, Climatization, Heat Pumps and DHW\",\"publisher\":{\"@id\":\"https:\/\/energie.pt\/en\/#organization\"},\"alternateName\":\"ENERGIE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energie.pt\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energie.pt\/en\/#organization\",\"name\":\"Energie - Thermodynamic Solar Energy\",\"alternateName\":\"Energie\",\"url\":\"https:\/\/energie.pt\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/energie.pt\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"width\":190,\"height\":55,\"caption\":\"Energie - Thermodynamic Solar Energy\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\",\"https:\/\/www.instagram.com\/energieportugal\/\",\"https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ\",\"https:\/\/www.linkedin.com\/company\/energieportugal\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energie.pt\/en\/#\/schema\/person\/db40e6f91190f7c107f522c91d27873d\",\"name\":\"catiarocha\",\"sameAs\":[\"https:\/\/energie.pt\/\"],\"url\":\"https:\/\/energie.pt\/en\/author\/catiarocha\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE - ENERGIE EST, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/","og_locale":"en_US","og_type":"article","og_title":"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE - ENERGIE EST, Lda.","og_description":"Une maison situ\u00e9e dans la r\u00e9gion de l\u2019Alto Minho, \u00e0 l&#8217;architecture moderne et avec une conception minimaliste, \u00e9quip\u00e9e d&#8217;un plancher radiant sous micro-ciment et d&#8217;un syst\u00e8me d&#8217;huisseries Cortizo. An integral solution of Central Heating and Hot Water was chosen as the main image of the intended concept. The residence was equipped with an integral Thermodynamic [&hellip;]","og_url":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/","og_site_name":"ENERGIE EST, Lda.","article_publisher":"https:\/\/www.facebook.com\/EnergiePortugalEst\/","article_published_time":"2017-03-13T14:22:49+00:00","article_modified_time":"2025-01-24T10:47:31+00:00","og_image":[{"width":1563,"height":826,"url":"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg","type":"image\/jpeg"}],"author":"catiarocha","twitter_card":"summary_large_image","twitter_misc":{"Written by":"catiarocha","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#article","isPartOf":{"@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/"},"author":{"name":"catiarocha","@id":"https:\/\/energie.pt\/en\/#\/schema\/person\/db40e6f91190f7c107f522c91d27873d"},"headline":"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE","datePublished":"2017-03-13T14:22:49+00:00","dateModified":"2025-01-24T10:47:31+00:00","mainEntityOfPage":{"@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/"},"wordCount":129,"commentCount":0,"publisher":{"@id":"https:\/\/energie.pt\/en\/#organization"},"image":{"@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg","articleSection":["News","World Energie"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/","url":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/","name":"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE - ENERGIE EST, Lda.","isPartOf":{"@id":"https:\/\/energie.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage"},"image":{"@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg","datePublished":"2017-03-13T14:22:49+00:00","dateModified":"2025-01-24T10:47:31+00:00","breadcrumb":{"@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#primaryimage","url":"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2017\/03\/newsletter_marco_2017_v_ENERGIE_Final_v2_CASESTUDY.jpg","width":1563,"height":826},{"@type":"BreadcrumbList","@id":"https:\/\/energie.pt\/en\/world-energie\/news\/reference-work-single-family-house\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"homepage","item":"https:\/\/energie.pt\/en\/"},{"@type":"ListItem","position":2,"name":"World Energie","item":"https:\/\/energie.pt\/en\/category\/world-energie\/"},{"@type":"ListItem","position":3,"name":"News","item":"https:\/\/energie.pt\/en\/category\/world-energie\/news\/"},{"@type":"ListItem","position":4,"name":"REFERENCE WORK \u2013 SINGLE FAMILY HOUSE"}]},{"@type":"WebSite","@id":"https:\/\/energie.pt\/en\/#website","url":"https:\/\/energie.pt\/en\/","name":"ENERGIE","description":"Thermodynamic Solar Energy Solutions, Climatization, Heat Pumps and DHW","publisher":{"@id":"https:\/\/energie.pt\/en\/#organization"},"alternateName":"ENERGIE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energie.pt\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/energie.pt\/en\/#organization","name":"Energie - Thermodynamic Solar Energy","alternateName":"Energie","url":"https:\/\/energie.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/energie.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","width":190,"height":55,"caption":"Energie - Thermodynamic Solar Energy"},"image":{"@id":"https:\/\/energie.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergiePortugalEst\/","https:\/\/www.instagram.com\/energieportugal\/","https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ","https:\/\/www.linkedin.com\/company\/energieportugal\/"]},{"@type":"Person","@id":"https:\/\/energie.pt\/en\/#\/schema\/person\/db40e6f91190f7c107f522c91d27873d","name":"catiarocha","sameAs":["https:\/\/energie.pt\/"],"url":"https:\/\/energie.pt\/en\/author\/catiarocha\/"}]}},"_links":{"self":[{"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/posts\/15345"}],"collection":[{"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/comments?post=15345"}],"version-history":[{"count":1,"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/posts\/15345\/revisions"}],"predecessor-version":[{"id":30647,"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/posts\/15345\/revisions\/30647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/media\/11237"}],"wp:attachment":[{"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/media?parent=15345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/categories?post=15345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energie.pt\/en\/wp-json\/wp\/v2\/tags?post=15345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}