{"id":23125,"date":"2023-12-18T15:57:09","date_gmt":"2023-12-18T15:57:09","guid":{"rendered":"https:\/\/energie.pt\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/"},"modified":"2025-01-22T11:29:51","modified_gmt":"2025-01-22T11:29:51","slug":"energie-es-nuevamente-pyme-lider","status":"publish","type":"post","link":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/","title":{"rendered":"ENERGIE ES NUEVAMENTE PYME L\u00cdDER"},"content":{"rendered":"\n<p>La noticia de la revalidaci\u00f3n de este estatus es tambi\u00e9n una afirmaci\u00f3n del reconocimiento a un esfuerzo constante durante m\u00e1s de 42 a\u00f1os.<\/p>\n\n<p>No es nada nuevo, pero es motivo de orgullo. Esta distinci\u00f3n fue concedida por la IAPMEI (Ag\u00eancia para a Competitividade e Inova\u00e7\u00e3o I.P.) en colaboraci\u00f3n con Turismo de Portugal, la banca y las Sociedades de Garant\u00eda Rec\u00edproca. Este estatus se cre\u00f3 para destacar e identificar a las PYME con un rendimiento superior, y para ENERGIE es una gran satisfacci\u00f3n que se reconozca p\u00fablicamente el \u00e9xito de su estrategia empresarial y su contribuci\u00f3n a la econom\u00eda nacional.<\/p>\n\n<p>Recibir de nuevo este premio es un honor que llena a todo el universo ENERGIE de un sentimiento de orgullo y gratitud. Deseamos expresar nuestro agradecimiento especial a nuestros empleados, cuyo compromiso y dedicaci\u00f3n son fundamentales para lograr este reconocimiento. Manifestamos asimismo nuestro sincero agradecimiento a todas las personas que se han implicado, depositando su confianza en nuestra empresa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La noticia de la revalidaci\u00f3n de este estatus es tambi\u00e9n una afirmaci\u00f3n del reconocimiento a un esfuerzo constante durante m\u00e1s de 42 a\u00f1os. No es nada nuevo, pero es motivo de orgullo. Esta distinci\u00f3n fue concedida por la IAPMEI (Ag\u00eancia para a Competitividade e Inova\u00e7\u00e3o I.P.) en colaboraci\u00f3n con Turismo de Portugal, la banca y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[265,137],"tags":[],"class_list":["post-23125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-energie","category-noticias"],"blocksy_meta":[],"acf":{"data_bimensal_da_noticia":"SEPTIEMBRE | OCTUBRE \/ 2023"},"cp_meta_data":{"_encloseme":["1"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_data_bimensal_da_noticia":["field_627e65cc70022"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_thumbnail_id":["23092"],"stackable_optimized_css":[""],"stackable_optimized_css_raw":["a:0:{}"],"_last_translation_edit_mode":["translation-editor"],"_yoast_wpseo_primary_category":["1"],"data_bimensal_da_noticia":["SEPTIEMBRE | OCTUBRE \/ 2023"],"_wpml_media_has_media":["1"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>ENERGIE ES NUEVAMENTE PYME L\u00cdDER - ENERGIE EST, Lda.<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"ENERGIE ES NUEVAMENTE PYME L\u00cdDER - ENERGIE EST, Lda.\" \/>\r\n<meta property=\"og:description\" content=\"La noticia de la revalidaci\u00f3n de este estatus es tambi\u00e9n una afirmaci\u00f3n del reconocimiento a un esfuerzo constante durante m\u00e1s de 42 a\u00f1os. No es nada nuevo, pero es motivo de orgullo. Esta distinci\u00f3n fue concedida por la IAPMEI (Ag\u00eancia para a Competitividade e Inova\u00e7\u00e3o I.P.) en colaboraci\u00f3n con Turismo de Portugal, la banca y [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/\" \/>\r\n<meta property=\"og:site_name\" content=\"ENERGIE EST, Lda.\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-12-18T15:57:09+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-01-22T11:29:51+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Serafim Paredes\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Serafim Paredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/\"},\"author\":{\"name\":\"Serafim Paredes\",\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176\"},\"headline\":\"ENERGIE ES NUEVAMENTE PYME L\u00cdDER\",\"datePublished\":\"2023-12-18T15:57:09+00:00\",\"dateModified\":\"2025-01-22T11:29:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/\"},\"wordCount\":180,\"publisher\":{\"@id\":\"https:\/\/energie.pt\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png\",\"articleSection\":[\"Mundo Energie\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/\",\"url\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/\",\"name\":\"ENERGIE ES NUEVAMENTE PYME L\u00cdDER - ENERGIE EST, Lda.\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png\",\"datePublished\":\"2023-12-18T15:57:09+00:00\",\"dateModified\":\"2025-01-22T11:29:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png\",\"width\":1920,\"height\":1080,\"caption\":\"lider\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina principal\",\"item\":\"https:\/\/energie.pt\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mundo Energie\",\"item\":\"https:\/\/energie.pt\/es\/category\/mundo-energie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Noticias\",\"item\":\"https:\/\/energie.pt\/es\/category\/mundo-energie\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ENERGIE ES NUEVAMENTE PYME L\u00cdDER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energie.pt\/es\/#website\",\"url\":\"https:\/\/energie.pt\/es\/\",\"name\":\"ENERGIE\",\"description\":\"Soluciones de Energ\u00eda Solar Termodin\u00e1mica, Climatizaci\u00f3n, Bombas de Calor y ACS\",\"publisher\":{\"@id\":\"https:\/\/energie.pt\/es\/#organization\"},\"alternateName\":\"ENERGIE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energie.pt\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energie.pt\/es\/#organization\",\"name\":\"Energie - Thermodynamic Solar Energy\",\"alternateName\":\"Energie\",\"url\":\"https:\/\/energie.pt\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"width\":190,\"height\":55,\"caption\":\"Energie - Thermodynamic Solar Energy\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\",\"https:\/\/www.instagram.com\/energieportugal\/\",\"https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ\",\"https:\/\/www.linkedin.com\/company\/energieportugal\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176\",\"name\":\"Serafim Paredes\",\"sameAs\":[\"https:\/\/energie.pt\/\"],\"url\":\"https:\/\/energie.pt\/es\/author\/serafim\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENERGIE ES NUEVAMENTE PYME L\u00cdDER - ENERGIE EST, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/","og_locale":"es_ES","og_type":"article","og_title":"ENERGIE ES NUEVAMENTE PYME L\u00cdDER - ENERGIE EST, Lda.","og_description":"La noticia de la revalidaci\u00f3n de este estatus es tambi\u00e9n una afirmaci\u00f3n del reconocimiento a un esfuerzo constante durante m\u00e1s de 42 a\u00f1os. No es nada nuevo, pero es motivo de orgullo. Esta distinci\u00f3n fue concedida por la IAPMEI (Ag\u00eancia para a Competitividade e Inova\u00e7\u00e3o I.P.) en colaboraci\u00f3n con Turismo de Portugal, la banca y [&hellip;]","og_url":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/","og_site_name":"ENERGIE EST, Lda.","article_publisher":"https:\/\/www.facebook.com\/EnergiePortugalEst\/","article_published_time":"2023-12-18T15:57:09+00:00","article_modified_time":"2025-01-22T11:29:51+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png","type":"image\/png"}],"author":"Serafim Paredes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Serafim Paredes","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#article","isPartOf":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/"},"author":{"name":"Serafim Paredes","@id":"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176"},"headline":"ENERGIE ES NUEVAMENTE PYME L\u00cdDER","datePublished":"2023-12-18T15:57:09+00:00","dateModified":"2025-01-22T11:29:51+00:00","mainEntityOfPage":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/"},"wordCount":180,"publisher":{"@id":"https:\/\/energie.pt\/es\/#organization"},"image":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png","articleSection":["Mundo Energie","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/","url":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/","name":"ENERGIE ES NUEVAMENTE PYME L\u00cdDER - ENERGIE EST, Lda.","isPartOf":{"@id":"https:\/\/energie.pt\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage"},"image":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png","datePublished":"2023-12-18T15:57:09+00:00","dateModified":"2025-01-22T11:29:51+00:00","breadcrumb":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#primaryimage","url":"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2023\/12\/liderlandscape-1.png","width":1920,"height":1080,"caption":"lider"},{"@type":"BreadcrumbList","@id":"https:\/\/energie.pt\/es\/mundo-energie\/noticias\/energie-es-nuevamente-pyme-lider\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina principal","item":"https:\/\/energie.pt\/es\/"},{"@type":"ListItem","position":2,"name":"Mundo Energie","item":"https:\/\/energie.pt\/es\/category\/mundo-energie\/"},{"@type":"ListItem","position":3,"name":"Noticias","item":"https:\/\/energie.pt\/es\/category\/mundo-energie\/noticias\/"},{"@type":"ListItem","position":4,"name":"ENERGIE ES NUEVAMENTE PYME L\u00cdDER"}]},{"@type":"WebSite","@id":"https:\/\/energie.pt\/es\/#website","url":"https:\/\/energie.pt\/es\/","name":"ENERGIE","description":"Soluciones de Energ\u00eda Solar Termodin\u00e1mica, Climatizaci\u00f3n, Bombas de Calor y ACS","publisher":{"@id":"https:\/\/energie.pt\/es\/#organization"},"alternateName":"ENERGIE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energie.pt\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/energie.pt\/es\/#organization","name":"Energie - Thermodynamic Solar Energy","alternateName":"Energie","url":"https:\/\/energie.pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","width":190,"height":55,"caption":"Energie - Thermodynamic Solar Energy"},"image":{"@id":"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergiePortugalEst\/","https:\/\/www.instagram.com\/energieportugal\/","https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ","https:\/\/www.linkedin.com\/company\/energieportugal\/"]},{"@type":"Person","@id":"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176","name":"Serafim Paredes","sameAs":["https:\/\/energie.pt\/"],"url":"https:\/\/energie.pt\/es\/author\/serafim\/"}]}},"_links":{"self":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts\/23125"}],"collection":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/comments?post=23125"}],"version-history":[{"count":1,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts\/23125\/revisions"}],"predecessor-version":[{"id":29957,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts\/23125\/revisions\/29957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/media\/23092"}],"wp:attachment":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/media?parent=23125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/categories?post=23125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/tags?post=23125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}