{"id":31564,"date":"2025-06-13T10:49:27","date_gmt":"2025-06-13T10:49:27","guid":{"rendered":"https:\/\/energie.pt\/mundo-energie\/noticias\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/"},"modified":"2025-06-13T10:57:50","modified_gmt":"2025-06-13T10:57:50","slug":"eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a","status":"publish","type":"post","link":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/","title":{"rendered":"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A"},"content":{"rendered":"\n<p>ENERGIE acaba de obtener la certificaci\u00f3n MCS (Microgeneration Certification Scheme) para sus Bombas de Calor Solares Termodin\u00e1micas de las gamas ECO y ECOTOP, que incorporan el nuevo gas refrigerante R513A, una alternativa m\u00e1s ecol\u00f3gica y energ\u00e9ticamente eficiente, destinadas a la producci\u00f3n de Agua Caliente Sanitaria (ACS).<\/p>\n\n<p>El gas refrigerante R513A, con un Potencial de Calentamiento Global (GWP) reducido, refuerza el compromiso de ENERGIE frente a los crecientes desaf\u00edos que plantean los cambios clim\u00e1ticos, en la b\u00fasqueda constante de soluciones que mitiguen el impacto ambiental sin comprometer el alto rendimiento y la fiabilidad que caracterizan a sus equipos.<\/p>\n\n<p>La certificaci\u00f3n MCS es una referencia internacional en t\u00e9rminos de calidad, rendimiento y conformidad t\u00e9cnica. El proceso de certificaci\u00f3n es riguroso e incluye no solo la evaluaci\u00f3n t\u00e9cnica de los productos, sino tambi\u00e9n un an\u00e1lisis exhaustivo del proceso de fabricaci\u00f3n, los materiales empleados, los procedimientos internos y la formaci\u00f3n de los equipos implicados.<\/p>\n\n<p>En el Reino Unido, la certificaci\u00f3n MCS es obligatoria para la comercializaci\u00f3n, instalaci\u00f3n y acceso a incentivos estatales relacionados con los sistemas de calefacci\u00f3n de agua. Con esta renovaci\u00f3n, ENERGIE consolida su posici\u00f3n como fabricante de referencia en los mercados brit\u00e1nico y europeo, promoviendo soluciones eficientes, sostenibles y certificadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ENERGIE acaba de obtener la certificaci\u00f3n MCS (Microgeneration Certification Scheme) para sus Bombas de Calor Solares Termodin\u00e1micas de las gamas ECO y ECOTOP, que incorporan el nuevo gas refrigerante R513A, una alternativa m\u00e1s ecol\u00f3gica y energ\u00e9ticamente eficiente, destinadas a la producci\u00f3n de Agua Caliente Sanitaria (ACS). El gas refrigerante R513A, con un Potencial de Calentamiento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[265,137],"tags":[],"class_list":["post-31564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-energie","category-noticias"],"blocksy_meta":[],"acf":{"data_bimensal_da_noticia":"MAYO | JUNIO \/ 2025"},"cp_meta_data":{"_encloseme":["1"],"_yoast_wpseo_primary_category":["130"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_data_bimensal_da_noticia":["field_627e65cc70022"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"data_bimensal_da_noticia":["MAYO | JUNIO \/ 2025"],"_thumbnail_id":["31521"],"stackable_optimized_css":[""],"stackable_optimized_css_raw":["a:0:{}"],"_last_translation_edit_mode":["translation-editor"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A - ENERGIE EST, Lda.<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A - ENERGIE EST, Lda.\" \/>\r\n<meta property=\"og:description\" content=\"ENERGIE acaba de obtener la certificaci\u00f3n MCS (Microgeneration Certification Scheme) para sus Bombas de Calor Solares Termodin\u00e1micas de las gamas ECO y ECOTOP, que incorporan el nuevo gas refrigerante R513A, una alternativa m\u00e1s ecol\u00f3gica y energ\u00e9ticamente eficiente, destinadas a la producci\u00f3n de Agua Caliente Sanitaria (ACS). El gas refrigerante R513A, con un Potencial de Calentamiento [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/\" \/>\r\n<meta property=\"og:site_name\" content=\"ENERGIE EST, Lda.\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-06-13T10:49:27+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-06-13T10:57:50+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"900\" \/>\r\n\t<meta property=\"og:image:height\" content=\"478\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Serafim Paredes\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Serafim Paredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/\"},\"author\":{\"name\":\"Serafim Paredes\",\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176\"},\"headline\":\"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A\",\"datePublished\":\"2025-06-13T10:49:27+00:00\",\"dateModified\":\"2025-06-13T10:57:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\/\/energie.pt\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png\",\"articleSection\":[\"Mundo Energie\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/\",\"url\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/\",\"name\":\"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A - ENERGIE EST, Lda.\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png\",\"datePublished\":\"2025-06-13T10:49:27+00:00\",\"dateModified\":\"2025-06-13T10:57:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina principal\",\"item\":\"https:\/\/energie.pt\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mundo Energie\",\"item\":\"https:\/\/energie.pt\/es\/category\/mundo-energie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Noticias\",\"item\":\"https:\/\/energie.pt\/es\/category\/mundo-energie\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energie.pt\/es\/#website\",\"url\":\"https:\/\/energie.pt\/es\/\",\"name\":\"ENERGIE\",\"description\":\"Soluciones de Energ\u00eda Solar Termodin\u00e1mica, Climatizaci\u00f3n, Bombas de Calor y ACS\",\"publisher\":{\"@id\":\"https:\/\/energie.pt\/es\/#organization\"},\"alternateName\":\"ENERGIE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energie.pt\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energie.pt\/es\/#organization\",\"name\":\"Energie - Thermodynamic Solar Energy\",\"alternateName\":\"Energie\",\"url\":\"https:\/\/energie.pt\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"width\":190,\"height\":55,\"caption\":\"Energie - Thermodynamic Solar Energy\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\",\"https:\/\/www.instagram.com\/energieportugal\/\",\"https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ\",\"https:\/\/www.linkedin.com\/company\/energieportugal\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176\",\"name\":\"Serafim Paredes\",\"sameAs\":[\"https:\/\/energie.pt\/\"],\"url\":\"https:\/\/energie.pt\/es\/author\/serafim\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A - ENERGIE EST, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/","og_locale":"es_ES","og_type":"article","og_title":"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A - ENERGIE EST, Lda.","og_description":"ENERGIE acaba de obtener la certificaci\u00f3n MCS (Microgeneration Certification Scheme) para sus Bombas de Calor Solares Termodin\u00e1micas de las gamas ECO y ECOTOP, que incorporan el nuevo gas refrigerante R513A, una alternativa m\u00e1s ecol\u00f3gica y energ\u00e9ticamente eficiente, destinadas a la producci\u00f3n de Agua Caliente Sanitaria (ACS). El gas refrigerante R513A, con un Potencial de Calentamiento [&hellip;]","og_url":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/","og_site_name":"ENERGIE EST, Lda.","article_publisher":"https:\/\/www.facebook.com\/EnergiePortugalEst\/","article_published_time":"2025-06-13T10:49:27+00:00","article_modified_time":"2025-06-13T10:57:50+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png","type":"image\/png"}],"author":"Serafim Paredes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Serafim Paredes","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#article","isPartOf":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/"},"author":{"name":"Serafim Paredes","@id":"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176"},"headline":"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A","datePublished":"2025-06-13T10:49:27+00:00","dateModified":"2025-06-13T10:57:50+00:00","mainEntityOfPage":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/"},"wordCount":239,"publisher":{"@id":"https:\/\/energie.pt\/es\/#organization"},"image":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png","articleSection":["Mundo Energie","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/","url":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/","name":"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A - ENERGIE EST, Lda.","isPartOf":{"@id":"https:\/\/energie.pt\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage"},"image":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png","datePublished":"2025-06-13T10:49:27+00:00","dateModified":"2025-06-13T10:57:50+00:00","breadcrumb":{"@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#primaryimage","url":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/06\/23.06_MCS-CERTIFICADO.png","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/energie.pt\/es\/mundo-energie\/eco-y-ecotop-reciben-certificacion-mcs-con-nuevo-refrigerante-r513a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina principal","item":"https:\/\/energie.pt\/es\/"},{"@type":"ListItem","position":2,"name":"Mundo Energie","item":"https:\/\/energie.pt\/es\/category\/mundo-energie\/"},{"@type":"ListItem","position":3,"name":"Noticias","item":"https:\/\/energie.pt\/es\/category\/mundo-energie\/noticias\/"},{"@type":"ListItem","position":4,"name":"ECO Y ECOTOP RECIBEN CERTIFICACI\u00d3N MCS CON NUEVO REFRIGERANTE R513A"}]},{"@type":"WebSite","@id":"https:\/\/energie.pt\/es\/#website","url":"https:\/\/energie.pt\/es\/","name":"ENERGIE","description":"Soluciones de Energ\u00eda Solar Termodin\u00e1mica, Climatizaci\u00f3n, Bombas de Calor y ACS","publisher":{"@id":"https:\/\/energie.pt\/es\/#organization"},"alternateName":"ENERGIE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energie.pt\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/energie.pt\/es\/#organization","name":"Energie - Thermodynamic Solar Energy","alternateName":"Energie","url":"https:\/\/energie.pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","width":190,"height":55,"caption":"Energie - Thermodynamic Solar Energy"},"image":{"@id":"https:\/\/energie.pt\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergiePortugalEst\/","https:\/\/www.instagram.com\/energieportugal\/","https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ","https:\/\/www.linkedin.com\/company\/energieportugal\/"]},{"@type":"Person","@id":"https:\/\/energie.pt\/es\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176","name":"Serafim Paredes","sameAs":["https:\/\/energie.pt\/"],"url":"https:\/\/energie.pt\/es\/author\/serafim\/"}]}},"_links":{"self":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts\/31564"}],"collection":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/comments?post=31564"}],"version-history":[{"count":1,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts\/31564\/revisions"}],"predecessor-version":[{"id":31565,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/posts\/31564\/revisions\/31565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/media\/31521"}],"wp:attachment":[{"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/media?parent=31564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/categories?post=31564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energie.pt\/es\/wp-json\/wp\/v2\/tags?post=31564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}