{"id":33528,"date":"2025-12-04T16:25:36","date_gmt":"2025-12-04T16:25:36","guid":{"rendered":"https:\/\/energie.pt\/mondiale-energie\/notizia\/nuova-thermobox-duo-light\/"},"modified":"2025-12-10T08:29:48","modified_gmt":"2025-12-10T08:29:48","slug":"nuova-thermobox-duo-light","status":"publish","type":"post","link":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/","title":{"rendered":"NUOVA THERMOBOX DUO LIGHT"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-d6d1194\" data-block-id=\"d6d1194\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-d6d1194-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8593482\" data-v=\"4\" data-block-id=\"8593482\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8593482-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8593482-inner-blocks\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0153_1-1024x682.jpg\" alt=\"\" class=\"wp-image-33518\" srcset=\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0153_1-1024x682.jpg 1024w, https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0153_1-300x200.jpg 300w, https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0153_1-768x512.jpg 768w, https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0153_1.jpg 1109w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-56aaba2\" data-v=\"4\" data-block-id=\"56aaba2\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-56aaba2-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-56aaba2-inner-blocks\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0143_10-1024x683.jpg\" alt=\"\" class=\"wp-image-33513\" srcset=\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0143_10-1024x683.jpg 1024w, https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0143_10-300x200.jpg 300w, https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0143_10-768x512.jpg 768w, https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/IMG-20251120-WA0143_10.jpg 1077w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<p>ENERGIE presenta la nuova <strong>THERMOBOX DUO LIGHT<\/strong>: massima efficienza, compattezza e installazione semplificata.<\/p>\n\n<p>ENERGIE ha nuovamente innalzato gli standard della climatizzazione domestica presentando la <strong>THERMOBOX DUO LIGHT<\/strong>, una soluzione innovativa che combina efficienza energetica, risparmio di spazio e grande semplicit\u00e0 di installazione. Progettata per rendere il comfort domestico pi\u00f9 sostenibile e accessibile, questa unit\u00e0 interna per Pompe di Calore risponde alle esigenze attuali del mercato residenziale.<\/p>\n\n<p>La <strong>THERMOBOX DUO LIGHT<\/strong> integra, in un unico modulo, un serbatoio di Acqua Calda Sanitaria (ACS) e un serbatoio inerziale, creando un sistema Plug &amp; Play che ottimizza l\u2019intero processo di installazione. Progettata per essere 100% idraulica, elimina la gestione di gas fluorurati e include i principali componenti e accessori, riducendo costi, tempi di intervento e potenziali errori tecnici.<\/p>\n\n<p>L\u2019apparecchiatura \u00e8 stata sviluppata per essere incassata in mobili standard da 60&#215;60 cm, garantendo un\u2019integrazione discreta e armoniosa in qualsiasi ambiente interno, dalle abitazioni unifamiliari a quelle plurifamiliari. La separazione tra i due serbatoi aumenta ulteriormente la versatilit\u00e0, permettendo l\u2019uso del serbatoio inerziale per il raffrescamento estivo e assicurando comfort durante tutto l\u2019anno.<\/p>\n\n<p>La <strong>THERMOBOX DUO LIGHT<\/strong> \u00e8 disponibile in diverse configurazioni (160\/50 e 200\/50), offrendo soluzioni capaci di rispondere alle varie esigenze di climatizzazione e produzione di ACS, senza compromettere prestazioni ed efficienza energetica.<\/p>\n\n<p>Con questa novit\u00e0, ENERGIE rafforza ancora una volta il suo impegno verso l\u2019innovazione e la sostenibilit\u00e0, sviluppando tecnologie che uniscono affidabilit\u00e0, facilit\u00e0 d\u2019uso e alti standard di efficienza.<\/p>\n\n<p><strong>THERMOBOX DUO LIGHT<\/strong>, \u00a0la soluzione intelligente e sostenibile che semplifica il comfort della tua casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ENERGIE presenta la nuova THERMOBOX DUO LIGHT: massima efficienza, compattezza e installazione semplificata. ENERGIE ha nuovamente innalzato gli standard della climatizzazione domestica presentando la THERMOBOX DUO LIGHT, una soluzione innovativa che combina efficienza energetica, risparmio di spazio e grande semplicit\u00e0 di installazione. Progettata per rendere il comfort domestico pi\u00f9 sostenibile e accessibile, questa unit\u00e0 interna [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[264,138],"tags":[],"class_list":["post-33528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondiale-energie","category-notizia"],"blocksy_meta":{"disable_featured_image":"yes","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"acf":{"data_bimensal_da_noticia":"NOVEMBRE | DICEMBRE \/ 2025"},"cp_meta_data":{"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_data_bimensal_da_noticia":["field_627e65cc70022"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"data_bimensal_da_noticia":["NOVEMBRE | DICEMBRE \/ 2025"],"blocksy_post_meta_options":["a:2:{s:22:\"disable_featured_image\";s:3:\"yes\";s:17:\"styles_descriptor\";a:3:{s:6:\"styles\";a:3:{s:7:\"desktop\";s:0:\"\";s:6:\"tablet\";s:0:\"\";s:6:\"mobile\";s:0:\"\";}s:12:\"google_fonts\";a:0:{}s:7:\"version\";i:6;}}"],"_thumbnail_id":["33575"],"stackable_optimized_css":[""],"stackable_optimized_css_raw":["a:0:{}"],"_wpml_media_has_media":["1"],"_last_translation_edit_mode":["translation-editor"],"_yoast_wpseo_primary_category":["130"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>NUOVA THERMOBOX DUO LIGHT - ENERGIE EST, Lda.<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"NUOVA THERMOBOX DUO LIGHT - ENERGIE EST, Lda.\" \/>\r\n<meta property=\"og:description\" content=\"ENERGIE presenta la nuova THERMOBOX DUO LIGHT: massima efficienza, compattezza e installazione semplificata. ENERGIE ha nuovamente innalzato gli standard della climatizzazione domestica presentando la THERMOBOX DUO LIGHT, una soluzione innovativa che combina efficienza energetica, risparmio di spazio e grande semplicit\u00e0 di installazione. Progettata per rendere il comfort domestico pi\u00f9 sostenibile e accessibile, questa unit\u00e0 interna [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/\" \/>\r\n<meta property=\"og:site_name\" content=\"ENERGIE EST, Lda.\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-12-04T16:25:36+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-12-10T08:29:48+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:height\" content=\"573\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Serafim Paredes\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Serafim Paredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/\"},\"author\":{\"name\":\"Serafim Paredes\",\"@id\":\"https:\/\/energie.pt\/it\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176\"},\"headline\":\"NUOVA THERMOBOX DUO LIGHT\",\"datePublished\":\"2025-12-04T16:25:36+00:00\",\"dateModified\":\"2025-12-10T08:29:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\/\/energie.pt\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png\",\"articleSection\":[\"Mondiale Energie\",\"Notizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/\",\"url\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/\",\"name\":\"NUOVA THERMOBOX DUO LIGHT - ENERGIE EST, Lda.\",\"isPartOf\":{\"@id\":\"https:\/\/energie.pt\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png\",\"datePublished\":\"2025-12-04T16:25:36+00:00\",\"dateModified\":\"2025-12-10T08:29:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png\",\"width\":1080,\"height\":573},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\/\/energie.pt\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondiale Energie\",\"item\":\"https:\/\/energie.pt\/it\/category\/mondiale-energie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NUOVA THERMOBOX DUO LIGHT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energie.pt\/it\/#website\",\"url\":\"https:\/\/energie.pt\/it\/\",\"name\":\"ENERGIE\",\"description\":\"Soluzioni termodinamiche per l'energia solare, climatizzazione, pompe di calore e ACS\",\"publisher\":{\"@id\":\"https:\/\/energie.pt\/it\/#organization\"},\"alternateName\":\"ENERGIE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energie.pt\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energie.pt\/it\/#organization\",\"name\":\"Energie - Thermodynamic Solar Energy\",\"alternateName\":\"Energie\",\"url\":\"https:\/\/energie.pt\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/energie.pt\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"contentUrl\":\"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg\",\"width\":190,\"height\":55,\"caption\":\"Energie - Thermodynamic Solar Energy\"},\"image\":{\"@id\":\"https:\/\/energie.pt\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergiePortugalEst\/\",\"https:\/\/www.instagram.com\/energieportugal\/\",\"https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ\",\"https:\/\/www.linkedin.com\/company\/energieportugal\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energie.pt\/it\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176\",\"name\":\"Serafim Paredes\",\"sameAs\":[\"https:\/\/energie.pt\/\"],\"url\":\"https:\/\/energie.pt\/it\/author\/serafim\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUOVA THERMOBOX DUO LIGHT - ENERGIE EST, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/","og_locale":"it_IT","og_type":"article","og_title":"NUOVA THERMOBOX DUO LIGHT - ENERGIE EST, Lda.","og_description":"ENERGIE presenta la nuova THERMOBOX DUO LIGHT: massima efficienza, compattezza e installazione semplificata. ENERGIE ha nuovamente innalzato gli standard della climatizzazione domestica presentando la THERMOBOX DUO LIGHT, una soluzione innovativa che combina efficienza energetica, risparmio di spazio e grande semplicit\u00e0 di installazione. Progettata per rendere il comfort domestico pi\u00f9 sostenibile e accessibile, questa unit\u00e0 interna [&hellip;]","og_url":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/","og_site_name":"ENERGIE EST, Lda.","article_publisher":"https:\/\/www.facebook.com\/EnergiePortugalEst\/","article_published_time":"2025-12-04T16:25:36+00:00","article_modified_time":"2025-12-10T08:29:48+00:00","og_image":[{"width":1080,"height":573,"url":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png","type":"image\/png"}],"author":"Serafim Paredes","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Serafim Paredes","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#article","isPartOf":{"@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/"},"author":{"name":"Serafim Paredes","@id":"https:\/\/energie.pt\/it\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176"},"headline":"NUOVA THERMOBOX DUO LIGHT","datePublished":"2025-12-04T16:25:36+00:00","dateModified":"2025-12-10T08:29:48+00:00","mainEntityOfPage":{"@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/"},"wordCount":259,"publisher":{"@id":"https:\/\/energie.pt\/it\/#organization"},"image":{"@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png","articleSection":["Mondiale Energie","Notizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/","url":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/","name":"NUOVA THERMOBOX DUO LIGHT - ENERGIE EST, Lda.","isPartOf":{"@id":"https:\/\/energie.pt\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage"},"image":{"@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage"},"thumbnailUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png","datePublished":"2025-12-04T16:25:36+00:00","dateModified":"2025-12-10T08:29:48+00:00","breadcrumb":{"@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#primaryimage","url":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2025\/12\/NOV_DEZ_duo_light_v1.png","width":1080,"height":573},{"@type":"BreadcrumbList","@id":"https:\/\/energie.pt\/it\/mondiale-energie\/nuova-thermobox-duo-light\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/energie.pt\/it\/"},{"@type":"ListItem","position":2,"name":"Mondiale Energie","item":"https:\/\/energie.pt\/it\/category\/mondiale-energie\/"},{"@type":"ListItem","position":3,"name":"NUOVA THERMOBOX DUO LIGHT"}]},{"@type":"WebSite","@id":"https:\/\/energie.pt\/it\/#website","url":"https:\/\/energie.pt\/it\/","name":"ENERGIE","description":"Soluzioni termodinamiche per l'energia solare, climatizzazione, pompe di calore e ACS","publisher":{"@id":"https:\/\/energie.pt\/it\/#organization"},"alternateName":"ENERGIE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energie.pt\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/energie.pt\/it\/#organization","name":"Energie - Thermodynamic Solar Energy","alternateName":"Energie","url":"https:\/\/energie.pt\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/energie.pt\/it\/#\/schema\/logo\/image\/","url":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","contentUrl":"https:\/\/energie.pt\/wp-content\/uploads\/2021\/06\/logo_energie.svg","width":190,"height":55,"caption":"Energie - Thermodynamic Solar Energy"},"image":{"@id":"https:\/\/energie.pt\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergiePortugalEst\/","https:\/\/www.instagram.com\/energieportugal\/","https:\/\/www.youtube.com\/channel\/UCnItbF_zm_YZ1tFqzUcVgPQ","https:\/\/www.linkedin.com\/company\/energieportugal\/"]},{"@type":"Person","@id":"https:\/\/energie.pt\/it\/#\/schema\/person\/fbbc926447d5bcdd4272d1b2b459c176","name":"Serafim Paredes","sameAs":["https:\/\/energie.pt\/"],"url":"https:\/\/energie.pt\/it\/author\/serafim\/"}]}},"_links":{"self":[{"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/posts\/33528"}],"collection":[{"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/comments?post=33528"}],"version-history":[{"count":1,"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/posts\/33528\/revisions"}],"predecessor-version":[{"id":33529,"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/posts\/33528\/revisions\/33529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/media\/33575"}],"wp:attachment":[{"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/media?parent=33528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/categories?post=33528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energie.pt\/it\/wp-json\/wp\/v2\/tags?post=33528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}